{"id":1224,"date":"2022-11-16T12:08:25","date_gmt":"2022-11-16T12:08:25","guid":{"rendered":"https:\/\/camposerranoradio.com\/home\/?p=1224"},"modified":"2022-11-16T12:08:25","modified_gmt":"2022-11-16T12:08:25","slug":"cuerpo-de-bomberos-de-aguachica-recibio-dotacion-especializada-contra-incendios","status":"publish","type":"post","link":"https:\/\/camposerranoradio.com\/home\/2022\/11\/16\/cuerpo-de-bomberos-de-aguachica-recibio-dotacion-especializada-contra-incendios\/","title":{"rendered":"<strong>CUERPO DE BOMBEROS DE AGUACHICA RECIBI\u00d3 DOTACI\u00d3N ESPECIALIZADA CONTRA INCENDIOS<\/strong>"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Cuerpo de Bomberos de Aguachica recibi\u00f3 en la ciudad de Bogot\u00e1, en el D\u00eda Nacional del Bombero celebrado el pasado viernes once de noviembre, varios trajes especializados de protecci\u00f3n personal EPP para incendios estructurales como beneficio para el personal voluntariado de la instituci\u00f3n bomberil del municipio, con la finalidad de equipar y poder responder con excelencia a la hora de las emergencias presentadas en el municipio. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La comandante del Cuerpo de Bomberos, Beatriz Dur\u00e1n, fue la encargada de recibir en nombre del organismo de socorro de Aguachica por parte de la Direcci\u00f3n Nacional de Bomberos en coordinaci\u00f3n del Ministerio del Interior el equipamiento para acercamientos estructurales de incendios EPP, tambi\u00e9n conocidos como trajes de acercamiento, aproximaci\u00f3n y penetraci\u00f3n al fuego, dise\u00f1ados para soportar altas temperaturas mientras el bombero se enfrenta lo m\u00e1s cerca posible al eventual incendio, pues estos son elaborados con un material qu\u00edmico resistente al calor del fuego llamado Nomex.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Cuerpo de Bomberos de Aguachica recibi\u00f3 en la ciudad de Bogot\u00e1, en el D\u00eda Nacional del Bombero celebrado el pasado viernes once de noviembre, varios trajes especializados de protecci\u00f3n personal EPP para incendios estructurales como beneficio para el personal voluntariado de la instituci\u00f3n bomberil del municipio, con la finalidad de equipar y poder responder [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,13],"tags":[],"class_list":["post-1224","post","type-post","status-publish","format-standard","hentry","category-local","category-news"],"_links":{"self":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/1224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/comments?post=1224"}],"version-history":[{"count":1,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/1224\/revisions"}],"predecessor-version":[{"id":1226,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/1224\/revisions\/1226"}],"wp:attachment":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/media?parent=1224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/categories?post=1224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/tags?post=1224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}