{"id":1369,"date":"2022-11-28T12:27:17","date_gmt":"2022-11-28T12:27:17","guid":{"rendered":"https:\/\/camposerranoradio.com\/home\/?p=1369"},"modified":"2022-11-28T12:27:17","modified_gmt":"2022-11-28T12:27:17","slug":"fuerte-aguacero-del-sabado-causo-afectaciones-en-el-vox-coulvert-de-la-avenida-campo-serrano","status":"publish","type":"post","link":"https:\/\/camposerranoradio.com\/home\/2022\/11\/28\/fuerte-aguacero-del-sabado-causo-afectaciones-en-el-vox-coulvert-de-la-avenida-campo-serrano\/","title":{"rendered":"<strong>FUERTE AGUACERO DEL S\u00c1BADO CAUS\u00d3 AFECTACIONES EN EL VOX COULVERT DE LA AVENIDA CAMPO SERRANO<\/strong>"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Encima de la estructura de hierro actualmente hecha en el box coulvert ubicado en el asentamiento humano Las Vegas fue a dar un poste de alumbrado p\u00fablico auto derrumbado el s\u00e1bado 26 de noviembre en horas de la tarde en el desarrollo del fuerte aguacero presentado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El hecho dej\u00f3 sin servicio de luz al asentamiento humano en menci\u00f3n hasta ayer domingo en horas de la noche, cuando despu\u00e9s de las operaciones adelantadas por parte de CENS fue restablecido la prestaci\u00f3n del servicio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Simult\u00e1neamente, ayer domingo el representante de la contratista, ingeniero Yecid Medina y su equipo humano de trabajo, entr\u00f3 inmediatamente en acci\u00f3n al realizar una reuni\u00f3n ante la comunidad con la finalidad de dar un reporte oficial sobre las afectaciones e informando a los habitantes que de manera oportuna y con calidad se dar\u00e1 comienzo a la reparaci\u00f3n de imprevistos, haciendo principalmente limpieza en la obra y reemplazo de materiales obstruidos. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe resaltar que la nueva contratista Pinto S.A inici\u00f3 labores el pasado 19 de noviembre, desde entonces, el manhol de los barrios \u00c1lvaro Pallares se encuentra actualmente en etapa de culminaci\u00f3n y el vox coulvert con un alto porcentaje de avance, situaci\u00f3n que resalta la aceptaci\u00f3n de la comunidad ante la nueva firma constructora, quienes agradecen el inter\u00e9s de los ingenieros ante la visible posibilidad de finalizaci\u00f3n de la obra para el mes de diciembre de 2022.<\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/camposerranoradio.com\/home\/wp-content\/uploads\/2022\/11\/Ingeniero-Yecid-Medina-28-11-22.mp3\"><\/audio><figcaption class=\"wp-element-caption\"><strong>YECID MEDINA INGENIERO CONTRATISTA DE LA OBRA<\/strong><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"1372\" src=\"https:\/\/camposerranoradio.com\/home\/wp-content\/uploads\/2022\/11\/FUERTE-AGUACERO-DEL-SABADO-CAUSO-AFECTACIONES-EN-EL-VOX-COULVERT-DE-LA-AVENIDA-CAMPO-SERRANO-1.jpg\" alt=\"\" class=\"wp-image-1372\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"1371\" src=\"https:\/\/camposerranoradio.com\/home\/wp-content\/uploads\/2022\/11\/FUERTE-AGUACERO-DEL-SABADO-CAUSO-AFECTACIONES-EN-EL-VOX-COULVERT-DE-LA-AVENIDA-CAMPO-SERRANO-2.jpg\" alt=\"\" class=\"wp-image-1371\"\/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Encima de la estructura de hierro actualmente hecha en el box coulvert ubicado en el asentamiento humano Las Vegas fue a dar un poste de alumbrado p\u00fablico auto derrumbado el s\u00e1bado 26 de noviembre en horas de la tarde en el desarrollo del fuerte aguacero presentado. El hecho dej\u00f3 sin servicio de luz al asentamiento [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,13],"tags":[],"class_list":["post-1369","post","type-post","status-publish","format-standard","hentry","category-local","category-news"],"_links":{"self":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/1369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/comments?post=1369"}],"version-history":[{"count":1,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/1369\/revisions"}],"predecessor-version":[{"id":1373,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/1369\/revisions\/1373"}],"wp:attachment":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/media?parent=1369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/categories?post=1369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/tags?post=1369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}