{"id":486,"date":"2022-08-29T22:00:02","date_gmt":"2022-08-29T22:00:02","guid":{"rendered":"https:\/\/camposerranoradio.com\/home\/?p=486"},"modified":"2022-08-29T22:17:21","modified_gmt":"2022-08-29T22:17:21","slug":"juan-carlos-serpa-nuevo-presidente-de-asocomunal-aguachica","status":"publish","type":"post","link":"https:\/\/camposerranoradio.com\/home\/2022\/08\/29\/juan-carlos-serpa-nuevo-presidente-de-asocomunal-aguachica\/","title":{"rendered":"Juan Carlos Serpa nuevo presidente de Asocomunal Aguachica"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Asociaci\u00f3n de Juntas de Acci\u00f3n Comunal de Aguachica, ASOJUNTAS, tiene nuevo presidente, se trata del l\u00edder comunitario Juan Carlos Serpa, quien se inscribi\u00f3 por la plancha n\u00famero uno, logrando 169 votos, superando a la plancha n\u00famero dos que alcanzo 149 votos y la cual estaba representada por Julio Casadiegos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp; La elecci\u00f3n que se realiz\u00f3 el 28 de agosto, consolido la plancha de Juan Carlos Serpa al conseguir tambi\u00e9n la vicepresidencia, el fiscal, recreaci\u00f3n y deportes, comunicaci\u00f3n, planeaci\u00f3n, juventud, asuntos pol\u00edticos, mujer, adulto mayor, cultura, agropecuario, afrodecendiente, proyectos, asistencia t\u00e9cnica, y vivienda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0\u00a0\u00a0 Por su parte la plancha encabezada por Julio Casadiegos solamente consigui\u00f3 capacitaci\u00f3n, salud, ambiente, derechos humanos, asuntos \u00e9tnicos y servicios p\u00fablicos, tesorer\u00eda y secretaria.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/camposerranoradio.com\/home\/wp-content\/uploads\/2022\/08\/Juan-Carlos-Serpa-nuevo-presidente-de-Asocomunal-Aguachica.jpg\" alt=\"\" class=\"wp-image-487\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/elnuevosur.com\/2022\/08\/29\/juan-carlos-serpa-nuevo-presidente-de-asocomunal-aguachica\/\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Asociaci\u00f3n de Juntas de Acci\u00f3n Comunal de Aguachica, ASOJUNTAS, tiene nuevo presidente, se trata del l\u00edder comunitario Juan Carlos Serpa, quien se inscribi\u00f3 por la plancha n\u00famero uno, logrando 169 votos, superando a la plancha n\u00famero dos que alcanzo 149 votos y la cual estaba representada por Julio Casadiegos. &nbsp;&nbsp;&nbsp; La elecci\u00f3n que se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,13],"tags":[],"class_list":["post-486","post","type-post","status-publish","format-standard","hentry","category-local","category-news"],"_links":{"self":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/comments?post=486"}],"version-history":[{"count":1,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/486\/revisions"}],"predecessor-version":[{"id":488,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/486\/revisions\/488"}],"wp:attachment":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/media?parent=486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/categories?post=486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/tags?post=486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}