{"id":618,"date":"2022-09-21T23:11:46","date_gmt":"2022-09-21T23:11:46","guid":{"rendered":"https:\/\/camposerranoradio.com\/home\/?p=618"},"modified":"2022-09-21T23:11:48","modified_gmt":"2022-09-21T23:11:48","slug":"nuevo-inspector-de-policia-en-aguachica","status":"publish","type":"post","link":"https:\/\/camposerranoradio.com\/home\/2022\/09\/21\/nuevo-inspector-de-policia-en-aguachica\/","title":{"rendered":"NUEVO INSPECTOR DE POLIC\u00cdA EN AGUACHICA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Aguachica recibi\u00f3 el pasado siete de septiembre, al profesional Jos\u00e9 Mario Meneses Duarte, abogado de la Universidad Popular del Cesar sede Valledupar, Administrador p\u00fablico de la Escuela Superior de Administraci\u00f3n P\u00fablica de Valledupar, especialista en gesti\u00f3n p\u00fablica en la escuela de administraci\u00f3n p\u00fablica, como nuevo Inspector de Polic\u00eda, as\u00ed lo dio a conocer la Administraci\u00f3n Municipal el d\u00eda de ayer, martes 20 de septiembre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Meneses Duarte cuenta con nueve a\u00f1os de experiencia como Inspector de Polic\u00eda en el municipio de Pailitas, lugar en el cual, estuvo liderando adem\u00e1s, la comisar\u00eda de familia, de igual modo, por m\u00e1s de dos a\u00f1os, se desempe\u00f1\u00f3 como personero en el municipio de Pelaya.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe destacar que Meneses Duarte llega al cargo, dado a ser seleccionado en el proceso de convocatoria y meritocracia de la Comisi\u00f3n Nacional del Servicio Civil (CNSC). Dentro de sus funciones se encuentran principalmente, resolver mediante la conciliaci\u00f3n, aquellos problemas que surjan en el ejercicio de la convivencia ciudadana a trav\u00e9s de las normas de la Polic\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aguachica recibi\u00f3 el pasado siete de septiembre, al profesional Jos\u00e9 Mario Meneses Duarte, abogado de la Universidad Popular del Cesar sede Valledupar, Administrador p\u00fablico de la Escuela Superior de Administraci\u00f3n P\u00fablica de Valledupar, especialista en gesti\u00f3n p\u00fablica en la escuela de administraci\u00f3n p\u00fablica, como nuevo Inspector de Polic\u00eda, as\u00ed lo dio a conocer la Administraci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,13],"tags":[],"class_list":["post-618","post","type-post","status-publish","format-standard","hentry","category-local","category-news"],"_links":{"self":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/comments?post=618"}],"version-history":[{"count":1,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/618\/revisions"}],"predecessor-version":[{"id":620,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/618\/revisions\/620"}],"wp:attachment":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/media?parent=618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/categories?post=618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/tags?post=618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}