{"id":7294,"date":"2025-05-09T12:58:30","date_gmt":"2025-05-09T12:58:30","guid":{"rendered":"https:\/\/camposerranoradio.com\/home\/?p=7294"},"modified":"2025-05-09T12:58:30","modified_gmt":"2025-05-09T12:58:30","slug":"tres-expendedores-de-droga-fueron-capturados-con-sustancias-psicoactivas-y-un-arma-de-fuego-ilegal","status":"publish","type":"post","link":"https:\/\/camposerranoradio.com\/home\/2025\/05\/09\/tres-expendedores-de-droga-fueron-capturados-con-sustancias-psicoactivas-y-un-arma-de-fuego-ilegal\/","title":{"rendered":"TRES EXPENDEDORES DE DROGA FUERON CAPTURADOS CON SUSTANCIAS PSICOACTIVAS Y UN ARMA DE FUEGO ILEGAL"},"content":{"rendered":"\n<p class=\"has-text-align-left wp-block-paragraph\">La Polic\u00eda Nacional logr\u00f3 la captura en flagrancia de tres sujetos en el barrio Potos\u00ed del municipio de Aguachica, Cesar, como parte de una ofensiva contra el microtr\u00e1fico y el porte ilegal de armas. El operativo se llev\u00f3 a cabo cuando unidades policiales realizaban labores de patrullaje y control preventivo en la zona.<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Durante el procedimiento, los uniformados abordaron a tres hombres, cuyas edades oscilan entre los 30 y 32 a\u00f1os. Al realizarles un registro personal, hallaron en su poder una bolsa pl\u00e1stica que conten\u00eda 80 envolturas tipo cigarrillo, listas aparentemente para la venta, y un paquete rectangular, todos con sustancia vegetal que, tras pruebas preliminares, fue identificada como marihuana.<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Adem\u00e1s del alijo de droga, se les incaut\u00f3 un rev\u00f3lver calibre 38, el cual era portado sin el permiso ni documentaci\u00f3n legal exigida por la ley colombiana. Esta situaci\u00f3n agrav\u00f3 su situaci\u00f3n judicial, ya que tambi\u00e9n enfrentan cargos por fabricaci\u00f3n, tr\u00e1fico, porte o tenencia de armas de fuego, accesorios, partes o municiones.<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Seg\u00fan el teniente coronel Rodrigo Manrique, este procedimiento forma parte de la Estrategia Integral contra el Microtr\u00e1fico y la Delincuencia Com\u00fan, implementada para frenar el consumo y distribuci\u00f3n de sustancias psicoactivas en sectores residenciales. \u201cEstamos comprometidos con la seguridad de los barrios y no vamos a permitir que estas redes delictivas se sigan fortaleciendo en la regi\u00f3n\u201d, declar\u00f3 el oficial.<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Las autoridades locales resaltaron la importancia de este tipo de operativos, no solo por el decomiso de sustancias ilegales, sino tambi\u00e9n por la prevenci\u00f3n del uso de armas de fuego que podr\u00edan ser empleadas en hechos delictivos o violentos.<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Los tres capturados fueron trasladados a las instalaciones de la Fiscal\u00eda y puestos a disposici\u00f3n del sistema judicial, donde deber\u00e1n responder por los delitos imputados. Se espera que en las pr\u00f3ximas horas un juez de control de garant\u00edas determine si se les impone medida de aseguramiento mientras avanza el proceso judicial.<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">La Polic\u00eda reiter\u00f3 el llamado a la ciudadan\u00eda para que contin\u00fae denunciando cualquier actividad sospechosa relacionada con el tr\u00e1fico de estupefacientes o el porte de armas ilegales, garantizando absoluta reserva para quienes colaboren con informaci\u00f3n clave que permita desmantelar estas redes delictivas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Polic\u00eda Nacional logr\u00f3 la captura en flagrancia de tres sujetos en el barrio Potos\u00ed del municipio de Aguachica, Cesar, como parte de una ofensiva contra el microtr\u00e1fico y el porte ilegal de armas. El operativo se llev\u00f3 a cabo cuando unidades policiales realizaban labores de patrullaje y control preventivo en la zona. Durante el [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7295,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,11,13],"tags":[],"class_list":["post-7294","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-judicial","category-local","category-news"],"_links":{"self":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/7294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/comments?post=7294"}],"version-history":[{"count":1,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/7294\/revisions"}],"predecessor-version":[{"id":7296,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/7294\/revisions\/7296"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/media\/7295"}],"wp:attachment":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/media?parent=7294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/categories?post=7294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/tags?post=7294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}