{"id":762,"date":"2022-10-06T13:07:18","date_gmt":"2022-10-06T13:07:18","guid":{"rendered":"https:\/\/camposerranoradio.com\/home\/?p=762"},"modified":"2022-10-06T13:07:19","modified_gmt":"2022-10-06T13:07:19","slug":"un-menor-con-lesiones-de-consideracion-dejo-un-accidente-de-transito-en-aguachica","status":"publish","type":"post","link":"https:\/\/camposerranoradio.com\/home\/2022\/10\/06\/un-menor-con-lesiones-de-consideracion-dejo-un-accidente-de-transito-en-aguachica\/","title":{"rendered":"UN MENOR CON LESIONES DE CONSIDERACI\u00d3N DEJ\u00d3 UN ACCIDENTE DE TR\u00c1NSITO EN AGUACHICA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En horas de la ma\u00f1ana, de ayer mi\u00e9rcoles cinco de octubre, se registr\u00f3 nuevamente un accidente de tr\u00e1nsito en la carrera 14 con calle 3ra en Aguachica. Seg\u00fan se observa en un v\u00eddeo, un veh\u00edculo blanco modelo Tucson 2020, omiti\u00f3 presuntamente la se\u00f1al de tr\u00e1nsito de pare en la zona, impactando una motocicleta conducida por un se\u00f1or, en la que adem\u00e1s se movilizaba un menor de edad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este \u00faltimo, seg\u00fan versiones, recibi\u00f3 heridas de consideraci\u00f3n por lo que realizaron el llamado urgente a una ambulancia, sin embargo, frente a la demora, la infractora decidi\u00f3 asistir directamente al infante a un centro de salud.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En horas de la ma\u00f1ana, de ayer mi\u00e9rcoles cinco de octubre, se registr\u00f3 nuevamente un accidente de tr\u00e1nsito en la carrera 14 con calle 3ra en Aguachica. Seg\u00fan se observa en un v\u00eddeo, un veh\u00edculo blanco modelo Tucson 2020, omiti\u00f3 presuntamente la se\u00f1al de tr\u00e1nsito de pare en la zona, impactando una motocicleta conducida por [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,13],"tags":[],"class_list":["post-762","post","type-post","status-publish","format-standard","hentry","category-local","category-news"],"_links":{"self":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/comments?post=762"}],"version-history":[{"count":1,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/762\/revisions"}],"predecessor-version":[{"id":764,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/762\/revisions\/764"}],"wp:attachment":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/media?parent=762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/categories?post=762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/tags?post=762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}