{"id":8815,"date":"2025-10-24T12:47:06","date_gmt":"2025-10-24T12:47:06","guid":{"rendered":"https:\/\/camposerranoradio.com\/home\/?p=8815"},"modified":"2025-10-24T12:47:06","modified_gmt":"2025-10-24T12:47:06","slug":"una-esperanza-para-la-salud-mental-llega-la-ips-resurgir","status":"publish","type":"post","link":"https:\/\/camposerranoradio.com\/home\/2025\/10\/24\/una-esperanza-para-la-salud-mental-llega-la-ips-resurgir\/","title":{"rendered":"UNA ESPERANZA PARA LA SALUD MENTAL: LLEGA LA IPS RESURGIR"},"content":{"rendered":"\n<p class=\"has-text-align-left wp-block-paragraph\">La buena noticia lleg\u00f3 para el sur del Cesar y del sur de Bol\u00edvar; la comunidad del municipio y sus alrededores por fin contar\u00e1 con una instituci\u00f3n dedicada exclusivamente a la salud mental: la IPS Unidad Mental Resurgir S.A.S, un espacio que promete marcar un antes y un despu\u00e9s en la atenci\u00f3n a quienes enfrentan dificultades emocionales o psiqui\u00e1tricas.<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Con la autorizaci\u00f3n oficial de las autoridades de salud, la entidad se convierte en la primera del per\u00edmetro urbano en ofrecer urgencias psiqui\u00e1tricas las 24 horas, adem\u00e1s de hospitalizaci\u00f3n, laboratorio cl\u00ednico, farmacia y atenci\u00f3n a pacientes con conductas de consumo. Todo esto con el prop\u00f3sito de brindar una atenci\u00f3n integral y constante, sin necesidad de remisiones a otras ciudades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proyecto fue impulsado por un grupo de empresarios y profesionales locales que decidieron actuar frente a una necesidad que por a\u00f1os ha sido evidente: la falta de espacios especializados en salud mental. Su iniciativa busca ofrecer apoyo y acompa\u00f1amiento real a las familias que enfrentan este tipo de situaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Unidad Mental Resurgir funcionar\u00e1 en la calle 4\u00aa entre carreras 21 y 22, en un punto c\u00e9ntrico y de f\u00e1cil acceso. Con su apertura, la localidad da un paso importante hacia una atenci\u00f3n m\u00e1s humana, cercana y oportuna para todos los usuarios que requieran servicios psiqui\u00e1tricos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La buena noticia lleg\u00f3 para el sur del Cesar y del sur de Bol\u00edvar; la comunidad del municipio y sus alrededores por fin contar\u00e1 con una instituci\u00f3n dedicada exclusivamente a la salud mental: la IPS Unidad Mental Resurgir S.A.S, un espacio que promete marcar un antes y un despu\u00e9s en la atenci\u00f3n a quienes enfrentan [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8816,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,11,13],"tags":[],"class_list":["post-8815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","category-local","category-news"],"_links":{"self":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/8815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/comments?post=8815"}],"version-history":[{"count":1,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/8815\/revisions"}],"predecessor-version":[{"id":8817,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/8815\/revisions\/8817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/media\/8816"}],"wp:attachment":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/media?parent=8815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/categories?post=8815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/tags?post=8815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}