{"id":8830,"date":"2025-10-27T12:57:46","date_gmt":"2025-10-27T12:57:46","guid":{"rendered":"https:\/\/camposerranoradio.com\/home\/?p=8830"},"modified":"2025-10-27T12:57:46","modified_gmt":"2025-10-27T12:57:46","slug":"el-bosque-del-aguil-renace-jornada-de-limpieza-devuelve-la-vida-y-la-seguridad-al-sector","status":"publish","type":"post","link":"https:\/\/camposerranoradio.com\/home\/2025\/10\/27\/el-bosque-del-aguil-renace-jornada-de-limpieza-devuelve-la-vida-y-la-seguridad-al-sector\/","title":{"rendered":"EL BOSQUE DEL AG\u00dcIL RENACE: JORNADA DE LIMPIEZA DEVUELVE LA VIDA Y LA SEGURIDAD AL SECTOR"},"content":{"rendered":"\n<p class=\"has-text-align-left wp-block-paragraph\">El Bosque del Ag\u00fcil recuper\u00f3 su brillo tras una jornada de limpieza y embellecimiento que cambi\u00f3 por completo el aspecto del lugar. La actividad fue liderada por la Estaci\u00f3n de Polic\u00eda Aguachica, a trav\u00e9s del grupo de gesti\u00f3n comunitaria, y reuni\u00f3 a varias entidades comprometidas con mejorar la seguridad y el entorno ambiental del municipio.<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">La intervenci\u00f3n se realiz\u00f3 el pasado 24 de octubre en la calle 1 con carrera 12 del barrio El Bosque, dentro de la jurisdicci\u00f3n del CAI Campo Serrano. En esta ocasi\u00f3n participaron CORPOCESAR, la Secretar\u00eda de Planeaci\u00f3n (desde la secci\u00f3n de gesti\u00f3n ambiental) y la empresa VEOLIA, quienes sumaron esfuerzos para recuperar un punto que hab\u00eda sido afectado por el consumo de drogas y el abandono.<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Durante la jornada, los participantes instalaron letreros ecol\u00f3gicos con mensajes sobre el cuidado del medio ambiente, la importancia del reciclaje y la protecci\u00f3n de los recursos naturales, tambi\u00e9n se realizaron labores de ornato y limpieza que mejoraron la visibilidad y el aspecto del sector, convirti\u00e9ndolo en un espacio m\u00e1s agradable y seguro para las familias.<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">M\u00e1s de 500 personas entre ni\u00f1os, j\u00f3venes y adultos se beneficiaron directamente de esta iniciativa, que adem\u00e1s incluy\u00f3 charlas preventivas sobre el consumo de sustancias psicoactivas, con estas acciones, la Polic\u00eda Nacional y las entidades participantes reafirman su compromiso de trabajar junto a la comunidad por un municipio m\u00e1s limpio, sostenible y libre de drogas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Bosque del Ag\u00fcil recuper\u00f3 su brillo tras una jornada de limpieza y embellecimiento que cambi\u00f3 por completo el aspecto del lugar. La actividad fue liderada por la Estaci\u00f3n de Polic\u00eda Aguachica, a trav\u00e9s del grupo de gesti\u00f3n comunitaria, y reuni\u00f3 a varias entidades comprometidas con mejorar la seguridad y el entorno ambiental del municipio. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8831,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,11,13],"tags":[],"class_list":["post-8830","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","category-local","category-news"],"_links":{"self":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/8830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/comments?post=8830"}],"version-history":[{"count":1,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/8830\/revisions"}],"predecessor-version":[{"id":8832,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/8830\/revisions\/8832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/media\/8831"}],"wp:attachment":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/media?parent=8830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/categories?post=8830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/tags?post=8830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}