{"id":8887,"date":"2025-11-04T13:55:43","date_gmt":"2025-11-04T13:55:43","guid":{"rendered":"https:\/\/camposerranoradio.com\/home\/?p=8887"},"modified":"2025-11-04T13:55:43","modified_gmt":"2025-11-04T13:55:43","slug":"la-tradicional-fiesta-universitaria-de-la-upc-aguachica-cambia-de-lugar-pero-mantiene-su-esencia","status":"publish","type":"post","link":"https:\/\/camposerranoradio.com\/home\/2025\/11\/04\/la-tradicional-fiesta-universitaria-de-la-upc-aguachica-cambia-de-lugar-pero-mantiene-su-esencia\/","title":{"rendered":"LA TRADICIONAL FIESTA UNIVERSITARIA DE LA UPC AGUACHICA CAMBIA DE LUGAR, PERO MANTIENE SU ESENCIA"},"content":{"rendered":"\n<p class=\"has-text-align-left wp-block-paragraph\">En la Universidad Popular del Cesar, seccional Aguachica, todo est\u00e1 listo para la realizaci\u00f3n de la tradicional fiesta universitaria, una de las actividades m\u00e1s esperadas por los estudiantes cada a\u00f1o, que en esta oportunidad contar\u00e1 con un nuevo escenario y una programaci\u00f3n renovada.<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">El cambio de lugar ha generado comentarios entre algunos sectores externos a la instituci\u00f3n; sin embargo, la propuesta cuenta con el respaldo total de los estudiantes, quienes fueron los primeros en plantear la idea de traer una agrupaci\u00f3n reconocida y otros artistas invitados para esta edici\u00f3n.<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Seg\u00fan conoci\u00f3 este medio, la iniciativa fue socializada ante el Consejo de Programas y recibi\u00f3 el apoyo de la mayor\u00eda de los representantes estudiantiles. Debido a los costos que implica la contrataci\u00f3n de los artistas, se decidi\u00f3 implementar la venta de boletas como una alternativa para apoyar la financiaci\u00f3n del evento, sin que ello represente una obligaci\u00f3n para los asistentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La determinaci\u00f3n de no realizar la fiesta dentro del campus universitario responde a lo establecido en el Reglamento Estudiantil, que proh\u00edbe el consumo de alcohol en las instalaciones, y tambi\u00e9n a razones log\u00edsticas, ya que actualmente se desarrollan clases incluso los fines de semana, lo que dificultar\u00eda el proceso de limpieza posterior al evento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de los cambios, la esencia de la celebraci\u00f3n se mantiene intacta. En la tarde se llevar\u00e1 a cabo el tradicional Festival del Sancocho, y en la noche, la esperada fiesta universitaria con artistas invitados, en un espacio que busca fomentar la integraci\u00f3n, la alegr\u00eda y el esp\u00edritu participativo que caracteriza a la comunidad estudiantil de la UPC Aguachica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la Universidad Popular del Cesar, seccional Aguachica, todo est\u00e1 listo para la realizaci\u00f3n de la tradicional fiesta universitaria, una de las actividades m\u00e1s esperadas por los estudiantes cada a\u00f1o, que en esta oportunidad contar\u00e1 con un nuevo escenario y una programaci\u00f3n renovada. El cambio de lugar ha generado comentarios entre algunos sectores externos a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8889,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,11,13],"tags":[],"class_list":["post-8887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","category-local","category-news"],"_links":{"self":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/8887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/comments?post=8887"}],"version-history":[{"count":1,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/8887\/revisions"}],"predecessor-version":[{"id":8890,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/8887\/revisions\/8890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/media\/8889"}],"wp:attachment":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/media?parent=8887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/categories?post=8887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/tags?post=8887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}