{"id":9037,"date":"2025-11-19T12:25:32","date_gmt":"2025-11-19T12:25:32","guid":{"rendered":"https:\/\/camposerranoradio.com\/home\/?p=9037"},"modified":"2025-11-19T12:25:32","modified_gmt":"2025-11-19T12:25:32","slug":"registraduria-certifica-firmas-y-avala-la-realizacion-del-cabildo-abierto-en-aguachica","status":"publish","type":"post","link":"https:\/\/camposerranoradio.com\/home\/2025\/11\/19\/registraduria-certifica-firmas-y-avala-la-realizacion-del-cabildo-abierto-en-aguachica\/","title":{"rendered":"REGISTRADUR\u00cdA CERTIFICA FIRMAS Y AVALA LA REALIZACI\u00d3N DEL CABILDO ABIERTO EN AGUACHICA"},"content":{"rendered":"\n<p class=\"has-text-align-left wp-block-paragraph\">La Registradur\u00eda Nacional confirm\u00f3 la validez de las firmas recolectadas por la ciudadan\u00eda y certific\u00f3 que se cumplieron todos los requisitos para llevar a cabo un cabildo abierto en Aguachica, un mecanismo de participaci\u00f3n que permitir\u00e1 a los habitantes intervenir directamente en temas de inter\u00e9s comunitario.<\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">El concejal Jos\u00e9 Garc\u00eda, promotor de la iniciativa, inform\u00f3 que la certificaci\u00f3n lleg\u00f3 tras un proceso de recolecci\u00f3n de apoyos que se desarroll\u00f3 en diferentes sectores del municipio. De acuerdo con el corporado, la comunidad particip\u00f3 activamente durante las jornadas realizadas barrio a barrio, contribuyendo con las firmas necesarias para activar este derecho ciudadano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cabildo abierto es una herramienta contemplada en la Constituci\u00f3n que permite a los habitantes expresarse de manera directa ante las autoridades locales sobre asuntos que afectan a la comunidad. En este escenario, los ciudadanos pueden presentar propuestas, inquietudes y planteamientos, los cuales deben ser escuchados y respondidos por las entidades competentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la certificaci\u00f3n de la Registradur\u00eda, Aguachica queda oficialmente habilitada para avanzar hacia la etapa de convocatoria y organizaci\u00f3n del cabildo abierto, proceso que se anunciar\u00e1 p\u00fablicamente en los pr\u00f3ximos d\u00edas. Las autoridades deber\u00e1n definir fecha, lugar y metodolog\u00eda para garantizar la participaci\u00f3n amplia y transparente de la comunidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este paso representa un avance significativo para fortalecer los canales de participaci\u00f3n ciudadana y abrir espacios donde los habitantes puedan intervenir de manera directa en las decisiones p\u00fablicas del municipio.<\/p>\n\n\n\n<iframe src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=469&#038;href=https%3A%2F%2Fwww.facebook.com%2Freel%2F1817374858887046%2F&#038;show_text=false&#038;width=560&#038;t=0\" width=\"560\" height=\"469\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\" allowFullScreen=\"true\"><\/iframe>\n","protected":false},"excerpt":{"rendered":"<p>La Registradur\u00eda Nacional confirm\u00f3 la validez de las firmas recolectadas por la ciudadan\u00eda y certific\u00f3 que se cumplieron todos los requisitos para llevar a cabo un cabildo abierto en Aguachica, un mecanismo de participaci\u00f3n que permitir\u00e1 a los habitantes intervenir directamente en temas de inter\u00e9s comunitario. El concejal Jos\u00e9 Garc\u00eda, promotor de la iniciativa, inform\u00f3 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9038,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,11,13],"tags":[],"class_list":["post-9037","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","category-local","category-news"],"_links":{"self":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/9037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/comments?post=9037"}],"version-history":[{"count":1,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/9037\/revisions"}],"predecessor-version":[{"id":9039,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/posts\/9037\/revisions\/9039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/media\/9038"}],"wp:attachment":[{"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/media?parent=9037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/categories?post=9037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/camposerranoradio.com\/home\/wp-json\/wp\/v2\/tags?post=9037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}